{"id":242,"count":2,"description":"","link":"https:\/\/www.mosquetas.com\/en\/shop\/books\/","name":"BOOKS","slug":"books","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":14,"_links":{"self":[{"href":"https:\/\/www.mosquetas.com\/en\/wp-json\/wp\/v2\/product_cat\/242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mosquetas.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.mosquetas.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.mosquetas.com\/en\/wp-json\/wp\/v2\/product?product_cat=242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}